{"id":28655,"date":"2025-08-22T07:47:21","date_gmt":"2025-08-22T05:47:21","guid":{"rendered":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/?page_id=28655"},"modified":"2025-08-22T07:47:21","modified_gmt":"2025-08-22T05:47:21","slug":"cart","status":"publish","type":"page","link":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/en\/cart\/","title":{"rendered":"CART"},"content":{"rendered":"\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":12,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-28655","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CART - OPG FERBE\u017dAR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mesnica.gospodarstvo-ferbezar.com\/en\/cart\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CART - OPG FERBE\u017dAR\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mesnica.gospodarstvo-ferbezar.com\/en\/cart\/\" \/>\n<meta property=\"og:site_name\" content=\"OPG FERBE\u017dAR\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/en\\\/cart\\\/\",\"url\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/en\\\/cart\\\/\",\"name\":\"CART - OPG FERBE\u017dAR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/en\\\/#website\"},\"datePublished\":\"2025-08-22T05:47:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/en\\\/cart\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/en\\\/cart\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/en\\\/cart\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CART\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/en\\\/\",\"name\":\"OPG FERBE\u017dAR\",\"description\":\"OPG, gospodarstvo, uzgoj, doma\u0107a hrana\",\"publisher\":{\"@id\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/en\\\/#organization\",\"name\":\"OPG FERBE\u017dAR\",\"url\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo_200.png\",\"contentUrl\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo_200.png\",\"width\":231,\"height\":200,\"caption\":\"OPG FERBE\u017dAR\"},\"image\":{\"@id\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CART - OPG FERBE\u017dAR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/en\/cart\/","og_locale":"en_US","og_type":"article","og_title":"CART - OPG FERBE\u017dAR","og_url":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/en\/cart\/","og_site_name":"OPG FERBE\u017dAR","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/en\/cart\/","url":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/en\/cart\/","name":"CART - OPG FERBE\u017dAR","isPartOf":{"@id":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/en\/#website"},"datePublished":"2025-08-22T05:47:21+00:00","breadcrumb":{"@id":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/en\/cart\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mesnica.gospodarstvo-ferbezar.com\/en\/cart\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/en\/cart\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/en\/"},{"@type":"ListItem","position":2,"name":"CART"}]},{"@type":"WebSite","@id":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/en\/#website","url":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/en\/","name":"OPG FERBE\u017dAR","description":"OPG, gospodarstvo, uzgoj, doma\u0107a hrana","publisher":{"@id":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/en\/#organization","name":"OPG FERBE\u017dAR","url":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/wp-content\/uploads\/2021\/09\/logo_200.png","contentUrl":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/wp-content\/uploads\/2021\/09\/logo_200.png","width":231,"height":200,"caption":"OPG FERBE\u017dAR"},"image":{"@id":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/en\/wp-json\/wp\/v2\/pages\/28655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/en\/wp-json\/wp\/v2\/comments?post=28655"}],"version-history":[{"count":1,"href":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/en\/wp-json\/wp\/v2\/pages\/28655\/revisions"}],"predecessor-version":[{"id":28656,"href":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/en\/wp-json\/wp\/v2\/pages\/28655\/revisions\/28656"}],"wp:attachment":[{"href":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/en\/wp-json\/wp\/v2\/media?parent=28655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}