{"id":28304,"date":"2025-08-08T09:47:17","date_gmt":"2025-08-08T07:47:17","guid":{"rendered":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/product\/trocken-geschnittener-schinken-100g\/"},"modified":"2025-08-08T09:47:17","modified_gmt":"2025-08-08T07:47:17","slug":"trocken-geschnittener-schinken-100g","status":"publish","type":"product","link":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/de\/produkt\/trocken-geschnittener-schinken-100g\/","title":{"rendered":"Trocken geschnittener Schinken 100g"},"content":{"rendered":"<p>Es besteht die M\u00f6glichkeit, nur 6-8 kg, also den ganzen Schinken, zu bestellen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es besteht die M\u00f6glichkeit, nur 6-8 kg, also den ganzen Schinken, zu bestellen.<\/p>\n","protected":false},"featured_media":27975,"template":"","meta":[],"product_brand":[],"product_cat":[456,458],"product_tag":[],"class_list":["post-28304","product","type-product","status-publish","has-post-thumbnail","product_cat-schinken","product_cat-slawonischer-trockenschinken","first","instock","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trocken geschnittener Schinken 100g - OPG FERBE\u017dAR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mesnica.gospodarstvo-ferbezar.com\/de\/produkt\/trocken-geschnittener-schinken-100g\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trocken geschnittener Schinken 100g - OPG FERBE\u017dAR\" \/>\n<meta property=\"og:description\" content=\"Es besteht die M\u00f6glichkeit, nur 6-8 kg, also den ganzen Schinken, zu bestellen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mesnica.gospodarstvo-ferbezar.com\/de\/produkt\/trocken-geschnittener-schinken-100g\/\" \/>\n<meta property=\"og:site_name\" content=\"OPG FERBE\u017dAR\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mesnica.gospodarstvo-ferbezar.com\/wp-content\/uploads\/2025\/08\/c9356d10-2725-48b6-a857-5f575d79799d-773x1030-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"773\" \/>\n\t<meta property=\"og:image:height\" content=\"1030\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/de\\\/produkt\\\/trocken-geschnittener-schinken-100g\\\/\",\"url\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/de\\\/produkt\\\/trocken-geschnittener-schinken-100g\\\/\",\"name\":\"Trocken geschnittener Schinken 100g - OPG FERBE\u017dAR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/de\\\/produkt\\\/trocken-geschnittener-schinken-100g\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/de\\\/produkt\\\/trocken-geschnittener-schinken-100g\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/c9356d10-2725-48b6-a857-5f575d79799d-773x1030-1.jpg\",\"datePublished\":\"2025-08-08T07:47:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/de\\\/produkt\\\/trocken-geschnittener-schinken-100g\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/de\\\/produkt\\\/trocken-geschnittener-schinken-100g\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/de\\\/produkt\\\/trocken-geschnittener-schinken-100g\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/c9356d10-2725-48b6-a857-5f575d79799d-773x1030-1.jpg\",\"contentUrl\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/c9356d10-2725-48b6-a857-5f575d79799d-773x1030-1.jpg\",\"width\":773,\"height\":1030},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/de\\\/produkt\\\/trocken-geschnittener-schinken-100g\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GESCHAFT\",\"item\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/de\\\/geschaft\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Trocken geschnittener Schinken 100g\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/de\\\/\",\"name\":\"OPG FERBE\u017dAR\",\"description\":\"OPG, gospodarstvo, uzgoj, doma\u0107a hrana\",\"publisher\":{\"@id\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/de\\\/#organization\",\"name\":\"OPG FERBE\u017dAR\",\"url\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo_200.png\",\"contentUrl\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo_200.png\",\"width\":231,\"height\":200,\"caption\":\"OPG FERBE\u017dAR\"},\"image\":{\"@id\":\"https:\\\/\\\/mesnica.gospodarstvo-ferbezar.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trocken geschnittener Schinken 100g - OPG FERBE\u017dAR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/de\/produkt\/trocken-geschnittener-schinken-100g\/","og_locale":"de_DE","og_type":"article","og_title":"Trocken geschnittener Schinken 100g - OPG FERBE\u017dAR","og_description":"Es besteht die M\u00f6glichkeit, nur 6-8 kg, also den ganzen Schinken, zu bestellen.","og_url":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/de\/produkt\/trocken-geschnittener-schinken-100g\/","og_site_name":"OPG FERBE\u017dAR","og_image":[{"width":773,"height":1030,"url":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/wp-content\/uploads\/2025\/08\/c9356d10-2725-48b6-a857-5f575d79799d-773x1030-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/de\/produkt\/trocken-geschnittener-schinken-100g\/","url":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/de\/produkt\/trocken-geschnittener-schinken-100g\/","name":"Trocken geschnittener Schinken 100g - OPG FERBE\u017dAR","isPartOf":{"@id":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/de\/produkt\/trocken-geschnittener-schinken-100g\/#primaryimage"},"image":{"@id":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/de\/produkt\/trocken-geschnittener-schinken-100g\/#primaryimage"},"thumbnailUrl":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/wp-content\/uploads\/2025\/08\/c9356d10-2725-48b6-a857-5f575d79799d-773x1030-1.jpg","datePublished":"2025-08-08T07:47:17+00:00","breadcrumb":{"@id":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/de\/produkt\/trocken-geschnittener-schinken-100g\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mesnica.gospodarstvo-ferbezar.com\/de\/produkt\/trocken-geschnittener-schinken-100g\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/de\/produkt\/trocken-geschnittener-schinken-100g\/#primaryimage","url":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/wp-content\/uploads\/2025\/08\/c9356d10-2725-48b6-a857-5f575d79799d-773x1030-1.jpg","contentUrl":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/wp-content\/uploads\/2025\/08\/c9356d10-2725-48b6-a857-5f575d79799d-773x1030-1.jpg","width":773,"height":1030},{"@type":"BreadcrumbList","@id":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/de\/produkt\/trocken-geschnittener-schinken-100g\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/de\/"},{"@type":"ListItem","position":2,"name":"GESCHAFT","item":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/de\/geschaft\/"},{"@type":"ListItem","position":3,"name":"Trocken geschnittener Schinken 100g"}]},{"@type":"WebSite","@id":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/de\/#website","url":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/de\/","name":"OPG FERBE\u017dAR","description":"OPG, gospodarstvo, uzgoj, doma\u0107a hrana","publisher":{"@id":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/de\/#organization","name":"OPG FERBE\u017dAR","url":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/wp-content\/uploads\/2021\/09\/logo_200.png","contentUrl":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/wp-content\/uploads\/2021\/09\/logo_200.png","width":231,"height":200,"caption":"OPG FERBE\u017dAR"},"image":{"@id":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/de\/wp-json\/wp\/v2\/product\/28304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/de\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/de\/wp-json\/wp\/v2\/product\/28304\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/de\/wp-json\/wp\/v2\/media\/27975"}],"wp:attachment":[{"href":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/de\/wp-json\/wp\/v2\/media?parent=28304"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/de\/wp-json\/wp\/v2\/product_brand?post=28304"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/de\/wp-json\/wp\/v2\/product_cat?post=28304"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mesnica.gospodarstvo-ferbezar.com\/de\/wp-json\/wp\/v2\/product_tag?post=28304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}